{"id":3180,"date":"2020-07-08T15:27:16","date_gmt":"2020-07-08T13:27:16","guid":{"rendered":"http:\/\/www.horse-dental-equipment.com\/produit\/biothane-leather-straps\/"},"modified":"2025-06-23T13:56:21","modified_gmt":"2025-06-23T11:56:21","slug":"lanieres-ouvre-bouche-biothane","status":"publish","type":"product","link":"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/lanieres-ouvre-bouche-biothane\/","title":{"rendered":"Lani\u00e8res Ouvre-Bouche Biothane"},"content":{"rendered":"<p>Ces lani\u00e8res de remplacement s'adaptent \u00e0 l'ensemble des ouvre-bouches de la gamme HDE.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ces lani\u00e8res de remplacement s'adaptent \u00e0 l'ensemble des ouvre-bouches de la gamme HDE.<\/p>","protected":false},"featured_media":4595,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[88],"product_tag":[],"class_list":["post-3180","product","type-product","status-publish","has-post-thumbnail","product_cat-mouth-openers-accessories","first","instock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biothane Leather Straps - Horse Dental Equipment<\/title>\n<meta name=\"description\" content=\"This replacement straps is for all mouth-openers from HDE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/lanieres-ouvre-bouche-biothane\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biothane Leather Straps - Horse Dental Equipment\" \/>\n<meta property=\"og:description\" content=\"This replacement straps is for all mouth-openers from HDE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/lanieres-ouvre-bouche-biothane\/\" \/>\n<meta property=\"og:site_name\" content=\"Horse Dental Equipment\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T11:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/OB_010.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/\",\"name\":\"Biothane Leather Straps - Horse Dental Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/OB_010.png\",\"datePublished\":\"2020-07-08T13:27:16+00:00\",\"dateModified\":\"2025-06-23T11:56:21+00:00\",\"description\":\"This replacement straps is for all mouth-openers from HDE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/OB_010.png\",\"contentUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/OB_010.png\",\"width\":800,\"height\":619,\"caption\":\"Biothane Leather Straps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/biothane-leather-straps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biothane Leather Straps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\",\"name\":\"Horse Dental Equipment\",\"description\":\"Your partner to develop your equine dentistry business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lani\u00e8res Ouvre-Bouche Biothane - Horse Dental Equipment","description":"Ces lani\u00e8res de remplacement s'adaptent \u00e0 l'ensemble des ouvre-bouches de la gamme HDE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/lanieres-ouvre-bouche-biothane\/","og_locale":"fr_FR","og_type":"article","og_title":"Biothane Leather Straps - Horse Dental Equipment","og_description":"This replacement straps is for all mouth-openers from HDE.","og_url":"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/lanieres-ouvre-bouche-biothane\/","og_site_name":"Horse Dental Equipment","article_modified_time":"2025-06-23T11:56:21+00:00","og_image":[{"width":800,"height":619,"url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/OB_010.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/","url":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/","name":"Lani\u00e8res Ouvre-Bouche Biothane - Horse Dental Equipment","isPartOf":{"@id":"https:\/\/www.horse-dental-equipment.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/#primaryimage"},"image":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/OB_010.png","datePublished":"2020-07-08T13:27:16+00:00","dateModified":"2025-06-23T11:56:21+00:00","description":"Ces lani\u00e8res de remplacement s'adaptent \u00e0 l'ensemble des ouvre-bouches de la gamme HDE.","breadcrumb":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/#primaryimage","url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/OB_010.png","contentUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/OB_010.png","width":800,"height":619,"caption":"Biothane Leather Straps"},{"@type":"BreadcrumbList","@id":"https:\/\/www.horse-dental-equipment.com\/product\/biothane-leather-straps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.horse-dental-equipment.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.horse-dental-equipment.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Biothane Leather Straps"}]},{"@type":"WebSite","@id":"https:\/\/www.horse-dental-equipment.com\/#website","url":"https:\/\/www.horse-dental-equipment.com\/","name":"Horse Dental Equipment","description":"Your partner to develop your equine dentistry business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horse-dental-equipment.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product\/3180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/comments?post=3180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/media\/4595"}],"wp:attachment":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/media?parent=3180"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3180"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3180"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}