{"id":2973,"date":"2020-07-08T15:26:42","date_gmt":"2020-07-08T13:26:42","guid":{"rendered":"http:\/\/www.horse-dental-equipment.com\/produit\/11th-burr-straight\/"},"modified":"2026-04-01T15:44:55","modified_gmt":"2026-04-01T13:44:55","slug":"fraise-11emes-droite","status":"publish","type":"product","link":"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/fraise-11emes-droite\/","title":{"rendered":"Fraise 11\u00e8mes - Droite"},"content":{"rendered":"<p>Cette fraise est sp\u00e9cialement con\u00e7ue pour les 11\u00e8mes. La t\u00eate compacte, longue et \u00e9troite avec une hauteur r\u00e9duite (1 cm) facilite un acc\u00e8s optimal en fond de bouche.<br \/>\nDiff\u00e9rentes longueurs et formes de fraises et 2 options de protection de la t\u00eate diamant\u00e9e sont disponibles vous permettant de concevoir votre propre fraise.<br \/>\nCet instrument ne peut pas \u00eatre vendu sans protection.<\/p>","protected":false},"excerpt":{"rendered":"<p>Those handpieces are specially designed to work on the 11s. The compact, long and narrow head with a limited height (1 cm) facilitates an optimum access in the back of the mouth. Different handpiece&#8217;s lengths and shapes and 2 head protection options are available allowing you to design your own handpiece. This instrument can not [&hellip;]<\/p>\n","protected":false},"featured_media":4484,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[81,83],"product_tag":[],"class_list":["post-2973","product","type-product","status-publish","has-post-thumbnail","product_cat-individual-motorized-instruments","product_cat-specific-handpieces","pa_style-boho","pa_style-casual","first","instock","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>11s Handpiece - Straight - Horse Dental Equipment<\/title>\n<meta name=\"description\" content=\"Those handpieces are specially designed to work on the 11s. The compact, long and narrow head with a limited height (1 cm) facilitates an optimum access...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/fraise-11emes-droite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"11s Handpiece - Straight - Horse Dental Equipment\" \/>\n<meta property=\"og:description\" content=\"Those handpieces are specially designed to work on the 11s. The compact, long and narrow head with a limited height (1 cm) facilitates an optimum access...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/fraise-11emes-droite\/\" \/>\n<meta property=\"og:site_name\" content=\"Horse Dental Equipment\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T13:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/FRA_F11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/\",\"name\":\"11s Handpiece - Straight - Horse Dental Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FRA_F11.png\",\"datePublished\":\"2020-07-08T13:26:42+00:00\",\"dateModified\":\"2026-04-01T13:44:55+00:00\",\"description\":\"Those handpieces are specially designed to work on the 11s. The compact, long and narrow head with a limited height (1 cm) facilitates an optimum access...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FRA_F11.png\",\"contentUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/FRA_F11.png\",\"width\":800,\"height\":619,\"caption\":\"11s Handpiece - Straight\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/11s-handpiece-straight\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"11s Handpiece &#8211; Straight\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\",\"name\":\"Horse Dental Equipment\",\"description\":\"Your partner to develop your equine dentistry business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fraise 11\u00e8mes - Droite - Horse Dental Equipment","description":"Cette fraise est sp\u00e9cialement con\u00e7ue pour les 11\u00e8mes. La t\u00eate compacte, longue et \u00e9troite avec une hauteur r\u00e9duite (1 cm) facilite un acc\u00e8s optimal en fond de bouche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/fraise-11emes-droite\/","og_locale":"fr_FR","og_type":"article","og_title":"11s Handpiece - Straight - Horse Dental Equipment","og_description":"Those handpieces are specially designed to work on the 11s. The compact, long and narrow head with a limited height (1 cm) facilitates an optimum access...","og_url":"https:\/\/www.horse-dental-equipment.com\/fr\/produit\/fraise-11emes-droite\/","og_site_name":"Horse Dental Equipment","article_modified_time":"2026-04-01T13:44:55+00:00","og_image":[{"width":800,"height":619,"url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/FRA_F11.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/","url":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/","name":"Fraise 11\u00e8mes - Droite - Horse Dental Equipment","isPartOf":{"@id":"https:\/\/www.horse-dental-equipment.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/#primaryimage"},"image":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/FRA_F11.png","datePublished":"2020-07-08T13:26:42+00:00","dateModified":"2026-04-01T13:44:55+00:00","description":"Cette fraise est sp\u00e9cialement con\u00e7ue pour les 11\u00e8mes. La t\u00eate compacte, longue et \u00e9troite avec une hauteur r\u00e9duite (1 cm) facilite un acc\u00e8s optimal en fond de bouche.","breadcrumb":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/#primaryimage","url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/FRA_F11.png","contentUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/FRA_F11.png","width":800,"height":619,"caption":"11s Handpiece - Straight"},{"@type":"BreadcrumbList","@id":"https:\/\/www.horse-dental-equipment.com\/product\/11s-handpiece-straight\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.horse-dental-equipment.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.horse-dental-equipment.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"11s Handpiece &#8211; Straight"}]},{"@type":"WebSite","@id":"https:\/\/www.horse-dental-equipment.com\/#website","url":"https:\/\/www.horse-dental-equipment.com\/","name":"Horse Dental Equipment","description":"Your partner to develop your equine dentistry business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horse-dental-equipment.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/comments?post=2973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/media\/4484"}],"wp:attachment":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product_brand?post=2973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product_cat?post=2973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/product_tag?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}