{"id":9067,"date":"2022-05-17T17:19:17","date_gmt":"2022-05-17T15:19:17","guid":{"rendered":"http:\/\/www.horse-dental-equipment.com\/?post_type=mec-events&#038;p=9067"},"modified":"2022-05-17T17:31:44","modified_gmt":"2022-05-17T15:31:44","slug":"vet-austria","status":"publish","type":"mec-events","link":"https:\/\/www.horse-dental-equipment.com\/fr\/events\/vet-austria\/","title":{"rendered":"Vet Austria"},"content":{"rendered":"<h3>Herzlich willkommen zur hybriden 4. VET AUSTRIA 2022!<\/h3>\n<h4>DER \u00d6STERREICHISCHE BRANCHENTREFF F\u00dcR TIER\u00c4RZTE \/-INNEN physisch + digital<\/h4>\n<p>Seit dem Jahr 1984 findet in Salzburg die V\u00d6K Jahrestagung statt. Der Kongress ist mit mehr als 1000 Teilnehmern der gr\u00f6\u00dfte in seiner Art in \u00d6sterreich und damit ein absoluter Fixpunkt im Eventkalender, wenn es um Aus- und Weiterbildung, Wissentransfer, Smalltalk unter Kollegen sowie entdecken von Produktneuheiten geht.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.horse-dental-equipment.com\/fr\/contact\/\">Kontaktieren Sie uns<\/a> f\u00fcr weitere Informationen !<\/p>","protected":false},"excerpt":{"rendered":"<p>Herzlich willkommen zur hybriden 4. VET AUSTRIA 2022! DER \u00d6STERREICHISCHE BRANCHENTREFF F\u00dcR TIER\u00c4RZTE \/-INNEN physisch + digital Seit dem Jahr 1984 findet in Salzburg die V\u00d6K Jahrestagung statt. Der Kongress ist mit mehr als 1000 Teilnehmern der gr\u00f6\u00dfte in seiner Art in \u00d6sterreich und damit ein absoluter Fixpunkt im Eventkalender, wenn es um Aus- und [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9070,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[67],"class_list":["post-9067","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","mec_category-congress"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vet Austria - Horse Dental Equipment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horse-dental-equipment.com\/fr\/events\/vet-austria\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vet Austria - Horse Dental Equipment\" \/>\n<meta property=\"og:description\" content=\"Herzlich willkommen zur hybriden 4. VET AUSTRIA 2022! DER \u00d6STERREICHISCHE BRANCHENTREFF F\u00dcR TIER\u00c4RZTE \/-INNEN physisch + digital Seit dem Jahr 1984 findet in Salzburg die V\u00d6K Jahrestagung statt. Der Kongress ist mit mehr als 1000 Teilnehmern der gr\u00f6\u00dfte in seiner Art in \u00d6sterreich und damit ein absoluter Fixpunkt im Eventkalender, wenn es um Aus- und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horse-dental-equipment.com\/fr\/events\/vet-austria\/\" \/>\n<meta property=\"og:site_name\" content=\"Horse Dental Equipment\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-17T15:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1243\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/\",\"name\":\"Vet Austria - Horse Dental Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png\",\"datePublished\":\"2022-05-17T15:19:17+00:00\",\"dateModified\":\"2022-05-17T15:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png\",\"contentUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png\",\"width\":1243,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/vet-austria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vet Austria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\",\"name\":\"Horse Dental Equipment\",\"description\":\"Your partner to develop your equine dentistry business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vet Austria - Horse Dental Equipment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horse-dental-equipment.com\/fr\/events\/vet-austria\/","og_locale":"fr_FR","og_type":"article","og_title":"Vet Austria - Horse Dental Equipment","og_description":"Herzlich willkommen zur hybriden 4. VET AUSTRIA 2022! DER \u00d6STERREICHISCHE BRANCHENTREFF F\u00dcR TIER\u00c4RZTE \/-INNEN physisch + digital Seit dem Jahr 1984 findet in Salzburg die V\u00d6K Jahrestagung statt. Der Kongress ist mit mehr als 1000 Teilnehmern der gr\u00f6\u00dfte in seiner Art in \u00d6sterreich und damit ein absoluter Fixpunkt im Eventkalender, wenn es um Aus- und [&hellip;]","og_url":"https:\/\/www.horse-dental-equipment.com\/fr\/events\/vet-austria\/","og_site_name":"Horse Dental Equipment","article_modified_time":"2022-05-17T15:31:44+00:00","og_image":[{"width":1243,"height":570,"url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/","url":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/","name":"Vet Austria - Horse Dental Equipment","isPartOf":{"@id":"https:\/\/www.horse-dental-equipment.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/#primaryimage"},"image":{"@id":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png","datePublished":"2022-05-17T15:19:17+00:00","dateModified":"2022-05-17T15:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/#primaryimage","url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png","contentUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-17-a\u0300-17.11.14.png","width":1243,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/www.horse-dental-equipment.com\/events\/vet-austria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.horse-dental-equipment.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.horse-dental-equipment.com\/events\/"},{"@type":"ListItem","position":3,"name":"Vet Austria"}]},{"@type":"WebSite","@id":"https:\/\/www.horse-dental-equipment.com\/#website","url":"https:\/\/www.horse-dental-equipment.com\/","name":"Horse Dental Equipment","description":"Your partner to develop your equine dentistry business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horse-dental-equipment.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/mec-events\/9067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/comments?post=9067"}],"version-history":[{"count":0,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/mec-events\/9067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/media\/9070"}],"wp:attachment":[{"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/media?parent=9067"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/tags?post=9067"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/fr\/wp-json\/wp\/v2\/mec_category?post=9067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}