{"id":3052,"date":"2020-07-08T15:26:54","date_gmt":"2020-07-08T13:26:54","guid":{"rendered":"http:\/\/www.horse-dental-equipment.com\/produit\/evolution-battery-car-charger\/"},"modified":"2026-05-05T16:40:29","modified_gmt":"2026-05-05T14:40:29","slug":"cargador-coche-bateria-evolution","status":"publish","type":"product","link":"https:\/\/www.horse-dental-equipment.com\/es\/producto\/cargador-coche-bateria-evolution\/","title":{"rendered":"Cargador de Coche para Bater\u00eda Evolution"},"content":{"rendered":"<p>Cargador de coche para bater\u00eda Evolution.<\/p>\n<p><strong><a href=\"https:\/\/helium-connect.fr\/player\/54c6710f8d12a6546600000a\/fid\/69f9f4d93ca446f4bb6cc9af\">Rellene el formulario<\/a><\/strong>\u00a0para solicitar su cotizaci\u00f3n e ind\u00edquenos qu\u00e9 producto(s) de la categor\u00eda de\u00a0<strong>liquidaci\u00f3n<\/strong>\u00a0le interesa.<\/p>","protected":false},"excerpt":{"rendered":"<p>To charge the battery while travelling. Fill in the form\u00a0to request a quote and let us know which product(s) in the\u00a0destocking\u00a0category you are interested in.<\/p>","protected":false},"featured_media":4501,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[463,101,81],"product_tag":[],"class_list":["post-3052","product","type-product","status-publish","has-post-thumbnail","product_cat-destocking","product_cat-evolution-engine","product_cat-individual-motorized-instruments","first","instock","sale","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evolution Battery Car Charger - Horse Dental Equipment<\/title>\n<meta name=\"description\" content=\"To charge the battery while travelling.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horse-dental-equipment.com\/es\/producto\/cargador-coche-bateria-evolution\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evolution Battery Car Charger - Horse Dental Equipment\" \/>\n<meta property=\"og:description\" content=\"To charge the battery while travelling.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horse-dental-equipment.com\/es\/producto\/cargador-coche-bateria-evolution\/\" \/>\n<meta property=\"og:site_name\" content=\"Horse Dental Equipment\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T14:40:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/MEV_CVBE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/\",\"name\":\"Evolution Battery Car Charger - Horse Dental Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/MEV_CVBE.png\",\"datePublished\":\"2020-07-08T13:26:54+00:00\",\"dateModified\":\"2026-05-05T14:40:29+00:00\",\"description\":\"To charge the battery while travelling.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/MEV_CVBE.png\",\"contentUrl\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/MEV_CVBE.png\",\"width\":800,\"height\":619,\"caption\":\"Evolution Battery Car Charger\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/product\\\/evolution-battery-car-charger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evolution Battery Car Charger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/#website\",\"url\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/\",\"name\":\"Horse Dental Equipment\",\"description\":\"Your partner to develop your equine dentistry business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horse-dental-equipment.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cargador de Coche para Bater\u00eda Evolution - Horse Dental Equipment","description":"Cargador de coche para bater\u00eda Evolution.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horse-dental-equipment.com\/es\/producto\/cargador-coche-bateria-evolution\/","og_locale":"es_ES","og_type":"article","og_title":"Evolution Battery Car Charger - Horse Dental Equipment","og_description":"To charge the battery while travelling.","og_url":"https:\/\/www.horse-dental-equipment.com\/es\/producto\/cargador-coche-bateria-evolution\/","og_site_name":"Horse Dental Equipment","article_modified_time":"2026-05-05T14:40:29+00:00","og_image":[{"width":800,"height":619,"url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/MEV_CVBE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/","url":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/","name":"Cargador de Coche para Bater\u00eda Evolution - Horse Dental Equipment","isPartOf":{"@id":"https:\/\/www.horse-dental-equipment.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/#primaryimage"},"image":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/MEV_CVBE.png","datePublished":"2020-07-08T13:26:54+00:00","dateModified":"2026-05-05T14:40:29+00:00","description":"Cargador de coche para bater\u00eda Evolution.","breadcrumb":{"@id":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/#primaryimage","url":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/MEV_CVBE.png","contentUrl":"https:\/\/www.horse-dental-equipment.com\/wp-content\/uploads\/2020\/07\/MEV_CVBE.png","width":800,"height":619,"caption":"Evolution Battery Car Charger"},{"@type":"BreadcrumbList","@id":"https:\/\/www.horse-dental-equipment.com\/product\/evolution-battery-car-charger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.horse-dental-equipment.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.horse-dental-equipment.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Evolution Battery Car Charger"}]},{"@type":"WebSite","@id":"https:\/\/www.horse-dental-equipment.com\/#website","url":"https:\/\/www.horse-dental-equipment.com\/","name":"Horse Dental Equipment","description":"Your partner to develop your equine dentistry business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horse-dental-equipment.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/product\/3052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/comments?post=3052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/media\/4501"}],"wp:attachment":[{"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/media?parent=3052"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/product_brand?post=3052"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/product_cat?post=3052"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horse-dental-equipment.com\/es\/wp-json\/wp\/v2\/product_tag?post=3052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}